{"id":296,"date":"2021-04-15T18:03:01","date_gmt":"2021-04-15T18:03:01","guid":{"rendered":"https:\/\/cardriverentcar.com\/alquiler-de-vehiculos-guayaquil\/?p=296"},"modified":"2021-04-15T18:07:58","modified_gmt":"2021-04-15T18:07:58","slug":"plan-de-vacunacion-guayaquil-cardriverentcar","status":"publish","type":"post","link":"https:\/\/cardriverentcar.com\/alquiler-de-vehiculos-guayaquil\/2021\/04\/15\/plan-de-vacunacion-guayaquil-cardriverentcar\/","title":{"rendered":"Plan de vacunaci\u00f3n Guayaquil-cardriverentcar"},"content":{"rendered":"<p>Municipio de Guayaquil inicia vacunaci\u00f3n con 1.300 adultos mayores El Municipio de Guayaquil comenzar\u00e1 a inmunizar contra el Covid-19 con las dosis que le entregar\u00e1 el Gobierno Central, en medio de un repunte de muertes y contagios. El Municipio de Guayaquil comenzar\u00e1 el 13 de abril a inmunizar a la poblaci\u00f3n con las vacunas que le provea el Gobierno Central el martes, cuando la ciudad sufre un repunte de muertes y contagios por Covid-19. Seg\u00fan el \u00faltimo reporte municipal, en la semana comprendida entre el 4 y el 11 de abril se registraron 30 muertes diarias por la enfermedad. El 60% de los fallecidos tiene 65 a\u00f1os o m\u00e1s. Espa\u00f1a detiene a \u00abla se\u00f1ora\u00bb fugitiva ecuatoriana buscada por EE.UU. Tambi\u00e9n se inform\u00f3 que 160 personas se contagian al d\u00eda, lo que mantiene ocupadas al 100% las unidades de terapia intensiva de los hospitales p\u00fablicos y privados de la ciudad. \u201cEmpezamos la vacunaci\u00f3n con las vacunas que da el Gobierno Central\u201c, dijo la alcaldesa Cynthia Viteri. \u201cRecuerden siempre, Gobierno da vacunas, Gobierno da la lista, Municipio, la log\u00edstica\u201d. Record\u00f3 que el proceso se iniciar\u00e1 con 1.300 personas de la tercera edad. El Ministerio de Salud ofreci\u00f3 1.300 vacunas de Sinovac para la primera jornada de inmunizaci\u00f3n, la que se realizar\u00e1 en dos puntos habilitados por el municipio. El Municipio de Guayaquil firm\u00f3 con el Ministerio un convenio en el que la alcald\u00eda recibe las vacunas a cambio de capacitar a 1.000 personas para atender a los pacientes y habilitar siete puntos de vacunaci\u00f3n. Los m\u00e9dicos del Municipio solicitaron a las personas que lleguen 15 minutos antes de la hora de la cita y que acudan acompa\u00f1ados por personas que puedan asistirlos en el proceso de vacunaci\u00f3n. Guayaquil eval\u00faa nuevas restricciones Viteri sostendr\u00e1 una reuni\u00f3n con el COE Nacional para analizar la situaci\u00f3n de la pandemia en Guayaquil y, en conjunto, tomar medidas que permitan aplanar la curva de contagios. La cita est\u00e1 fijada para el mi\u00e9rcoles 14 de abril en las instalaciones del ECU 911. \u201cEl mi\u00e9rcoles, y en conjunto con el COE Nacional, tomaremos las medidas que la ciudad requiera para proteger a sus habitantes\u201d, dijo la alcaldesa y record\u00f3 que el COE Nacional tiene competencia en cuanto a movilidad de personas. Guayaquil, dentro de sus facultades, restringi\u00f3 la circulaci\u00f3n vehicular desde las 22:00 hasta las 05:00 del d\u00eda siguiente, medida que no afecta a personas de la primera l\u00ednea, comercio y abastecimiento. \u201cLa situaci\u00f3n epidemiol\u00f3gica sigue siendo preocupante\u201c, coment\u00f3 Carlos Farhat, epidemi\u00f3logo municipal. \u201cHay una incidencia de 3,7 casos por cada 10.000 habitantes, lo que significa que la semana pasada se enfermaron 160 personas por d\u00eda\u201c. \u201cEso corresponde a 1.120 personas en la semana\u201c, finaliz\u00f3.<\/p>\n<p><small>Para hacer uso de este contenido cite la fuente y haga un enlace a la nota original en Primicias.ec:\u00a0<a href=\"https:\/\/www.primicias.ec\/noticias\/sociedad\/guayaquil-inicia-vacunas-covid\/\">https:\/\/www.primicias.ec\/noticias\/sociedad\/guayaquil-inicia-vacunas-covid\/<\/a><\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Municipio de Guayaquil inicia vacunaci\u00f3n con 1.300 adultos mayores El Municipio de Guayaquil comenzar\u00e1 a inmunizar contra el Covid-19 con&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"_links":{"self":[{"href":"https:\/\/cardriverentcar.com\/alquiler-de-vehiculos-guayaquil\/wp-json\/wp\/v2\/posts\/296"}],"collection":[{"href":"https:\/\/cardriverentcar.com\/alquiler-de-vehiculos-guayaquil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cardriverentcar.com\/alquiler-de-vehiculos-guayaquil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cardriverentcar.com\/alquiler-de-vehiculos-guayaquil\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cardriverentcar.com\/alquiler-de-vehiculos-guayaquil\/wp-json\/wp\/v2\/comments?post=296"}],"version-history":[{"count":2,"href":"https:\/\/cardriverentcar.com\/alquiler-de-vehiculos-guayaquil\/wp-json\/wp\/v2\/posts\/296\/revisions"}],"predecessor-version":[{"id":298,"href":"https:\/\/cardriverentcar.com\/alquiler-de-vehiculos-guayaquil\/wp-json\/wp\/v2\/posts\/296\/revisions\/298"}],"wp:attachment":[{"href":"https:\/\/cardriverentcar.com\/alquiler-de-vehiculos-guayaquil\/wp-json\/wp\/v2\/media?parent=296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cardriverentcar.com\/alquiler-de-vehiculos-guayaquil\/wp-json\/wp\/v2\/categories?post=296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cardriverentcar.com\/alquiler-de-vehiculos-guayaquil\/wp-json\/wp\/v2\/tags?post=296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}